{"id":1110,"date":"2020-12-13T10:58:18","date_gmt":"2020-12-13T09:58:18","guid":{"rendered":"https:\/\/gradido.net\/?p=1110"},"modified":"2021-06-07T18:54:29","modified_gmt":"2021-06-07T16:54:29","slug":"episode-1","status":"publish","type":"post","link":"https:\/\/gradido.net\/bg\/episode-1\/","title":{"rendered":"\u041f\u043e\u0434\u043a\u0430\u0441\u0442\u044a\u0442 Gradido \u0437\u0430\u043f\u043e\u0447\u0432\u0430 \u0441 \u0432\u044a\u043b\u043d\u0435\u043d\u0438\u0435, \u043d\u0430\u0434\u0435\u0436\u0434\u0430 \u0438 \u0434\u0438\u043d\u0430\u043c\u0438\u0442"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1110\" class=\"elementor elementor-1110\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-496e1d53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"496e1d53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-461d7be0\" data-id=\"461d7be0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd9ebe2 elementor-widget elementor-widget-text-editor\" data-id=\"cd9ebe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Neue Wege in eine bessere Welt<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f93e3c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f93e3c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a9dfd19\" data-id=\"5a9dfd19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cdb6b8 elementor-widget elementor-widget-html\" data-id=\"9cdb6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script class=\"podigee-podcast-player\" src=\"https:\/\/cdn.podigee.com\/podcast-player\/javascripts\/podigee-podcast-player.js\" data-configuration=\"https:\/\/gradido.podigee.io\/1-neue-episode\/embed?context=external\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-585c640 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"585c640\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13c250b\" data-id=\"13c250b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0561949 elementor-widget elementor-widget-text-editor\" data-id=\"0561949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Corona-Krise zwingt uns zur Besinnung auf das Wesentliche und birgt gleichzeitig die Chance zu einem Neubeginn. Gemeinsam brechen wir auf in eine neue Zeit, in der wir, unsere Kinder und alle Kinder der Welt in Frieden und Wohlstand leben k\u00f6nnen \u2013 im Einklang mit der Natur. In 20 Jahren Forschungsarbeit ist es der Gradido-Akademie f\u00fcr Wirtschaftsbionik gelungen, ein neues Geld- und Wirtschaftssystem zu entwickeln, das alle Menschen f\u00f6rdert, ihr volles Potential zu entfalten, um die brennenden Probleme der Menschheit ein f\u00fcr alle mal zu l\u00f6sen.<br \/>Michael M\u00e4rzheuser und Bernd H\u00fcckst\u00e4dt sprechen dar\u00fcber, wie alles begann, welche fatalen Fehler des alten Finanzsystems gel\u00f6st wurden und warum nicht nur die armen, sondern auch die reichen Menschen von Gradido profitieren werden. [39:20]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e0d795e\" data-id=\"e0d795e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c61bad elementor-widget elementor-widget-image\" data-id=\"8c61bad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-1024x1024.jpg\" class=\"attachment-large size-large wp-image-2663\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-1024x1024.jpg 1024w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-300x300.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-150x150.jpg 150w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-768x768.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere-12x12.jpg 12w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/06\/gradido_podcast_premiere.jpg 1400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d051609 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d051609\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13cc168\" data-id=\"13cc168\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b43b3ee elementor-widget elementor-widget-heading\" data-id=\"b43b3ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transkript ( automatisch \u00fcbersetzt)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-474427c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"474427c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6041f12\" data-id=\"6041f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d994a9f elementor-widget elementor-widget-text-editor\" data-id=\"d994a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>[00:00:00] Kreislauf des Lebens als Wirtschaftsmodell.<br \/>[00:00:06] Der Kreislauf des Lebens als Wirtschaftsmodell \u2013 ganz genau! Eine Gemeinwohl W\u00e4hrung als Gl\u00fcckskonzept.<br \/>[00:00:14] Klingt gut habe ich so noch nicht geh\u00f6rt. Ja heute ist Premiere Tag.<br \/>[00:00:23] F\u00fcr den ersten Gradido-Podcast.<br \/>[00:00:26] Wir melden uns aus K\u00fcnzelsau dem Sitz der Gradido Akademie dem Institut f\u00fcr Wirtschaft.<br \/>[00:00:35] K\u00fcnzelsau ist eine kleine beschauliche Kreisstadt des Hohenlohekreis ist im fr\u00e4nkisch gepr\u00e4gten Nordosten Baden.<br \/>[00:00:45] Bekannt ist der K\u00fcnzelsau \u00fcbrigens auch durch das Schrauben Imperium wird eines der gr\u00f6\u00dften Familienunternehmen.<br \/>[00:00:55] Und eben auch durch Gradido der nat\u00fcrlichen \u00d6konomie des Lebens f\u00fcr Wohlstand und Frieden auf unserer Welt und das in Einklang mit der Natur.<br \/>[00:01:06] Seit mehr als 20 Jahren wird hier in der Akademie f\u00fcr Wirtschaft Munich nach einem neuen Wirtschafts Finanz und Geldsystem geforscht.<br \/>[00:01:17] M\u00f6glich gemacht haben dass die beiden Gr\u00fcnder und Entwickler Margret Baier und Bernd H\u00fcckst\u00e4dt.<br \/>[00:01:23] Mit ihrer bahnbrechenden Idee aus dem nat\u00fcrlichen Kreislauf des Lebens.<br \/>[00:01:30] Evolution\u00e4res Wirtschaftsbund Geldsystem zu entwickeln.<br \/>[00:01:34] Vor dem Hintergrund der Corona Krise die unsere welcher in k\u00fcrzester Zeit grundlegend ver\u00e4ndert hat.<br \/>[00:01:42] Die Wirtschaftsbionik innovative l\u00f6sungsorientierte Antworten auf existentielle Fragen unserer Zeit.<br \/>[00:01:51] Bernd wie hat alles begonnen bei Gradido wie seid ihr.<br \/>[00:01:58] Margret und du \u00fcberhaupt dazu gekommen sich die Erfolgsmodelle der Natur mal genauer unter die Lupe zu nehmen und daraus eben auch Schl\u00fcsse zu ziehen f\u00fcr ein neues weltweites Wirtschafts und Geldsystem,<br \/>[00:02:13] das Krieg und Armut verhindern kann wie fing vor 20 Jahren alles an ja was war eigentlich letztendlich eure intention.<br \/>[00:02:23] Und Intension war zu forschen woher kommt das eigentlich dass wir auf der einen Seite diesen.<br \/>[00:02:31] Wahnsinnige Reichtum haben und auf der anderen Seite diese ganz katastrophale Armut weltweit.<br \/>[00:02:37] Und kennengelernt haben wir uns vor 20 Jahren wir waren beide.<br \/>[00:02:43] Mit der Thematik unterwegs also Margret hat unter anderen z.b. auch in Slums in Ecuador mit gelebt,<br \/>[00:02:50] ich habe mir diese Fragen schon in der Kindheit gestellt habe damals noch keine Antworten bekommen sie haben mich nie losgelassen,<br \/>[00:02:58] und als wir beide uns kennengelernt haben haben wir festgestellt wir wollen gemeinsam an dem Thema weiter forschen.<br \/>[00:03:07] Haben dann festgestellt dass wir somit den normalen logischen Denken nicht weitergekommen sind bis wir dann gemerkt haben.<br \/>[00:03:17] Die Natur funktioniert ja schon seit \u00fcber viereinhalb Milliarden Jahren und bringt Leben in \u00fcberfliesen erf\u00fclle vor.<br \/>[00:03:27] Und das war uns pl\u00f6tzlich klar ja wir m\u00fcssen gucken was macht die Natur richtig.<br \/>[00:03:33] Und was macht im Vergleich dazu was machen wir Menschen wenn man so will falsch die wir ja st\u00e4ndig Leben zerst\u00f6ren,<br \/>[00:03:40] da kam dann eben die Bionik<br \/>[00:03:43] als Leitidee in spiel Bionik Biologie und Technik ja schon im 16 Uhr jahrhundert er dachte Leonardo da Vinci Flugmaschinen nach dem Vorbild des vogelflugs<br \/>[00:03:57] und gilt damit quasi als Urvater der Bioniker und das war euer Ansatz letztendlich auch,<br \/>[00:04:03] genau das ist unser Ansatz zuschauen wie funktioniert die Natur das hat Leonardo da Vinci schon gemacht,<br \/>[00:04:11] und hat wunderbare Konstruktionen entwickeln k\u00f6nnen nach dem Vorbild der Natur,<br \/>[00:04:18] das machen heutzutage nahezu alle Techniker z.b. die Flugmaschinen also die Flugzeuge werden nachempfunden wie Vogelflug funktioniert.<br \/>[00:04:29] Wo ist noch weniger gemacht wird ist momentan im Bereich der Wirtschaft.<br \/>[00:04:34] Dieser Bereich Wirtschaft Bionik ist noch ein relativ junges Gebiet und das hat uns einfach gereizt jetzt zuschauen.<br \/>[00:04:44] Wie z.b. funktioniert die Natur wie macht die das dass die st\u00e4ndig Leben hervorbringt wie macht die dass es dass ich st\u00e4ndig w\u00e4chst m\u00f6chte meine die Wirtschaft mir ja gerne wachsen,<br \/>[00:04:59] aber auf der anderen Seite wird etwas ganz Wesentliches vergessen dass n\u00e4mlich in der Natur zum wachsen auch die Verg\u00e4nglichkeit geh\u00f6rt und erst wenn man diesen Kreislauf einbringen.<br \/>[00:05:11] Dann k\u00f6nnen wir wirklich nachhaltige Modelle entwickeln.<br \/>[00:05:17] Also wir haben sozusagen Naturgesetze,<br \/>[00:05:21] naturgegebene Abl\u00e4ufe und die dienen als Vorbild f\u00fcr erfolgreiche \u00f6konomische Prozesse damit der Ansatz ganz genau das ist der Ansatz zu schauen,<br \/>[00:05:35] diese Prozesse in der Natur wie kann man die \u00fcbertragen man kann nat\u00fcrlich nicht alles eins zu eins \u00fcbertragen denn,<br \/>[00:05:42] wir Menschen sind eine besondere Spezies wir sind nicht so wie alle anderen Tiere auch das hei\u00dft man kann immer nur schauen was funktioniert in der Natur,<br \/>[00:05:53] und was l\u00e4sst sich davon \u00fcbertragen auf unserer Gesellschaft auf unsere Wirtschaft auf unser Zusammenleben und die Menschen sind ja auch noch ein bisschen mehr als Tiere.<br \/>[00:06:03] Wir sind besondere TV Bionik gegen Weltwirtschaftskrise wie muss man sich das vorstellen schl\u00e4gt jetzt sozusagen die Stunde der Wirtschaftsbionik.<br \/>[00:06:17] Jetzt wird auf jeden Fall mal klar dass das alte System so nicht funktionieren kann.<br \/>[00:06:26] Uns war das zwar schon vor 20 Jahren klar das ist auf die Dauer nicht funktionieren kann und das ist crashen muss,<br \/>[00:06:32] wie nat\u00fcrlich dann so einen Crash aussieht das konnten wir nicht vorher sagen wir wussten nur es wird ein Crash oder etwas \u00e4hnliches eben kommen,<br \/>[00:06:42] und ja jetzt sind wir ja mittendrin in der Korona Krise wo was reden dass du ziemlich alles gegen die Wand gefahren wird und das ganze wegen eines klitzekleinen Virus.<br \/>[00:06:56] Also die.<br \/>[00:06:57] Weltweite Wirtschaftskrise schafft eben nicht nur die Notwendigkeit zum Umdenken sondern macht auch die Fragilit\u00e4t ne des herrschenden Wirtschafts und Finanzsystem deutlich.<br \/>[00:07:09] Genau wir haben im Wirtschaftssystem ja dadurch dass es auf exponentiellen Wachstum aufgebaut ist.<br \/>[00:07:17] Du brauchst eben Fragilit\u00e4t anders hei\u00dft als Zerbrechlichkeit,<br \/>[00:07:21] ein System was nur sich in einer Richtung bewegt muss zwangsl\u00e4ufig fragil also zerbrechlich sein w\u00e4hrend die Natur ja auf Ausgleich raus ist das hei\u00dft also.<br \/>[00:07:34] So wie B\u00e4ume z.b. im Wind im Sturm stehen bleiben dich ganz stark.<br \/>[00:07:39] Hin und her schwanken k\u00f6nnen oder auch Grashalme diese Elastizit\u00e4t die Macht die Natur.<br \/>[00:07:47] W\u00e4hrend wir Menschen unsere Schwierigkeiten haben zum Beispiel ein Turm zu bauen der muss schon ganz sch\u00f6n viel Statik haben und sehr viel mehr Masse Einsatz haben dass er einem Wind und einem Sturm eben standhalten kann.<br \/>[00:08:01] Gradido schaut,<br \/>[00:08:03] auf die Erfolgsmodelle der Natur die sich eben bereits seit viereinhalb Milliarden Jahren bew\u00e4hren und das ist hochinteressant also folglich blickt die Gesellschaft,<br \/>[00:08:16] erwartungsvoller.<br \/>[00:08:19] Auf diesem Jahr noch junge Wissenschaft im Wirtschafts Bionik aber hier kommen die Antworten her letzendlich,<br \/>[00:08:29] aus der Natur die k\u00f6nnen nur aus der Natur also es gibt nichts was so wunderbar funktioniert,<br \/>[00:08:36] wie die Natur es gibt da ein sch\u00f6nes Sprichwort das hei\u00dft jeder dumme Junge kann einen K\u00e4fer zertreten aber es gibt kein Professor auf der Welt der einen bauen k\u00f6nnte.<br \/>[00:08:46] Forschungsst\u00e4tte f\u00fcr Freidenker kann man sagen ist die Akademie in K\u00fcnzelsau,<br \/>[00:08:55] und da stellt sich zun\u00e4chst einmal hatte ich die Frage Gradido oder Gradido.<br \/>[00:09:03] Das ist quasi ein Kunst name,<br \/>[00:09:06] na setzt sich zusammen aus gerade tut er Dankbarkeit dignit\u00e9 w\u00fcrde ja und donation was soviel hei\u00dft wie Geschenk oder Gabe der passt das jetzt alles<br \/>[00:09:20] zusammen f\u00fcr ein neues Finanz Wirtschaft und Geldsystem,<br \/>[00:09:25] diese drei wesentlichen Elemente aus der Natur.<br \/>[00:09:31] Nun in der Natur gibt es Schenkwirtschaft also es gibt in der Natur kein Geld das ist eine Binsenwahrheit in der Natur ist jedes Wesen lebt seinem Wesen entsprechend.<br \/>[00:09:45] Und wenn man so will schenkt es anderen Wesen und z.b. eine Blume schenkt der Biene Pollen und Nektar und so weiter,<br \/>[00:09:53] Die Biene schenkt dann wieder,<br \/>[00:09:55] den Nektar den sie gesammelt hat innerhalb ihres Bienenstaates dann wieder der Gemeinschaft des sind alles schenkt Prozesse wir kommen also,<br \/>[00:10:06] in der Entwicklung vom alten kaufen und bezahlen was eben unnat\u00fcrlich ist hin zu einem Schr\u00e4nken.<br \/>[00:10:14] Und dank und in der Mitte steht die w\u00fcrde man die W\u00fcrde des Menschen ist unantastbar so steht&#8217;s im Grundgesetz Erdbeben und auch zurecht steht es dort es geht ja darum Wirtschaft ist ja f\u00fcr Menschen,<br \/>[00:10:29] gemacht sodass wir Menschen ein menschenw\u00fcrdiges miteinander leben k\u00f6nnen ne,<br \/>[00:10:36] und das wiederum bedeutet es muss wirklich w\u00fcrdig sein.<br \/>[00:10:41] Und das was wir momentan auf der Erde erleben nat\u00fcrlich viele Menschen leben ein w\u00fcrdiges Dasein,<br \/>[00:10:48] aber eben die Mehrheit eben leider nicht zwei Drittel der Menschheit leben unterhalb der Armutsgrenze und dann kann von Menschenw\u00fcrde bisher noch keine Rede sein.<br \/>[00:10:57] Jeden Tag sterben 25.000 Menschen in Armut also ist total traurig und er hat mich auch immer wieder traurig ehrlich diese Zahl h\u00f6re.<br \/>[00:11:07] Und ja ja das gilt ist also jetzt wirklich zu beenden zumal wir Menschen,<br \/>[00:11:14] in der Lage sind also etwa die doppelte Menschenmenge also jetzt haben wir so um die in knapp 80 Jahren gibt da verschiedene Sch\u00e4tzungen aber die doppelte bis dreifache Menschenmenge k\u00f6nnten wir an ihren,<br \/>[00:11:26] sogar in biologisch hoher Qualit\u00e4t war nicht mehr so viel Fleisch essen ist klar,<br \/>[00:11:31] aber das wird man sowieso ges\u00fcnder wenn man weniger Fleisch isst das hei\u00dft also wir haben im Moment kein wirkliches \u00fcber bev\u00f6lkerungsproblem.<br \/>[00:11:40] Sondern eher ein Verteilungsproblem dass wir.<br \/>[00:11:44] Daf\u00fcr sorgen dass alle leben k\u00f6nnen und vor allen in Einklang mit der Natur im Einklang mit der Natur hei\u00dft letztendlich.<br \/>[00:11:53] Ja den Kreislauf des Lebens als Wirtschaftsmodell.<br \/>[00:11:58] Der Kreislauf des Lebens als Wirtschaftsmodell ganz genau eine Gemeinwohl W\u00e4hrung als gl\u00fcckskonzept.<br \/>[00:12:06] Das klingt gut habe ich schon noch nicht geh\u00f6rt also eine Gemeinwohl W\u00e4hrung.<br \/>[00:12:14] Hat die Akademie hast du mit der Margrit entwickelt.<br \/>[00:12:20] Genau Mann bringt sich in die Gemeinschaft ein also die Idee bei der Gemeinwohl W\u00e4hrung ist ein sogenanntes aktives Grundeinkommen.<br \/>[00:12:28] Was auf bedingungsloser Teilhabe beruht das bedeutet jeder Mensch egal welches Alters kann sich einbringen in die Gemeinschaft hat also das verbriefte Recht sich einzubringen.<br \/>[00:12:41] Und daf\u00fcr sein aktives Grundeinkommen zu verdienen.<br \/>[00:12:46] 20 Gradido pro Stunde 50 Stunden im Monat so haben wir es erstmal konzipiert das hei\u00dft also tausend Candido was etwa so viel ist wie 1000 \u20ac f\u00fcr jeden Menschen sowohl f\u00fcr Kinder Erwachsene und auch f\u00fcr alte Menschen<br \/>[00:13:00] wobei wir bei den alten Menschen sogar noch.<br \/>[00:13:03] Eine Variable Altersgrenze mit eingebaut haben also das alte Menschen wesentlich mehr dann als Grundeinkommen haben,<br \/>[00:13:11] k\u00f6nnen also die Rente ist auch gesichert bei Gardinen sehr sehr interessant auch vor dem Hintergrund der Diskussion des bedingungslosen Grundeinkommens also wir haben es hier letztendlich mit einem,<br \/>[00:13:23] aktiven Grundeinkommen Zutun exakt ja das bedingungslose Grundeinkommen ist ja,<br \/>[00:13:28] Gie\u00dfkannenprinzip also man gehst mit der Kanne egal auf alle Menschen dieselbe Summe damit ist zwar<br \/>[00:13:38] erstmal daf\u00fcr gesorgt oder w\u00e4re wenn sowas eingef\u00fchrt w\u00fcrde daf\u00fcr gesorgt dass jeder eine bestimmte Menge Geld im Monat hat<br \/>[00:13:46] aber es ist noch nicht daf\u00fcr gesorgt und hier f\u00e4ngt der Charme vom aktiven Grundeinkommen an das n\u00e4mlich.<br \/>[00:13:55] Das aktive Grundeinkommen die Menschen f\u00f6rdert und fordert das hei\u00dft jeder darf sich ja mit seinen Gaben mit dem was er oder sie am liebsten macht in die Gemeinschaft einbringen,<br \/>[00:14:08] und die Gemeinschaft hat ein Interesse dass er da sieht es besonders gut macht und es gibt einen positiven r\u00fcckkopplungseffekt,<br \/>[00:14:16] so dass das was ich gerne tue und das was ich immer mehr wiederhole und wo ich auch noch von der Gemeinschaft gef\u00f6rdert werde das tue ich immer besser das hei\u00dft also da werde ich immer h\u00f6re,<br \/>[00:14:27] Qualit\u00e4t abliefern Talente werden gef\u00f6rdert Talente werden gef\u00f6rdert ja wir waren auch potentialentfaltung.<br \/>[00:14:37] Deflation oder Inflation.<br \/>[00:14:41] Geh\u00f6ren dann eigentlich der Vergangenheit an nicht also die Wirtschaft ist auch du hast es angesprochen.<br \/>[00:14:50] Wachsen wachsen wachsen essen bei Modell von Gradido vom Wachstumszwang befreit.<br \/>[00:14:57] Deflation Inflation sind ja wenn man so will Fehlentwicklung im alten System weil das alte System infragil ist und wenn es nicht ganz klar gesteuert wird,<br \/>[00:15:10] und es ist unm\u00f6glich es dauerhaft zu Steuer.<br \/>[00:15:13] Dann gleitet es in die eine oder die andere Richtung oder teilweise sogar in beide gleichzeitig also ganz paradox diese sogenannte Stagflation.<br \/>[00:15:23] Bei Gradido ist es ja ein Modell nach dem Vorbild der Natur,<br \/>[00:15:28] es ist ein sich selbstregulierendes System was daf\u00fcr sorgt dass wenn die Geldmenge steigt<br \/>[00:15:35] dass dadurch dass die Verg\u00e4nglichkeit mit eingebaut ist dass die Geldmenge sanft auch wieder immer an den Idealwerte angebracht wer man kann also sagen ist ein.<br \/>[00:15:45] Dynamisches Gleichgewicht wo es auch keine Blasen gibt was einfach sich nat\u00fcrlich entwickelt und nachhaltig also schafft.<br \/>[00:15:55] Ein fehlerhaftes Finanzsystem eben genau das was wir alle nicht haben wollen Hunger Armut und Krieg was sie gleich Vertreiber.<br \/>[00:16:05] Was sind denn die fatalen Fehler des akuten Finanzsystems 0 f\u00e4ngt an Fehler 1,<br \/>[00:16:15] dass das jetzige Geld etwa 97% des Geldes ist sogenanntes viral Geld das hei\u00dft es wird auf Konten Gesch\u00e4ft in Form von Zahlen im,<br \/>[00:16:27] Computer das w\u00e4re bis jetzt noch nicht schlimm schlimm sind die Regeln nach Dienst gesch\u00f6pft wird nehme ich es wird durch Schulden Gesch\u00e4ft das hei\u00dft also,<br \/>[00:16:36] alle Guthaben auf der Welt haben auf der anderen Seite genau dieselbe H\u00f6he auch Schulden,<br \/>[00:16:43] und damit kann es nicht zu Wohlstand f\u00fcr alle f\u00fchren dann auf der einen Seite flie\u00dfen die Guthaben immer mehr konzentrieren sich immer mehr an auf einiger weniger erreiche.<br \/>[00:16:54] Und auf der anderen Seite ja der Rest der Welt muss ich dann die Schulden teilen und dass wir Menschen es nicht so ganz so deutlich merken.<br \/>[00:17:04] Daf\u00fcr.<br \/>[00:17:06] Treten dann die Staaten stellvertretend ein und deshalb werden die Staatsschulden immer h\u00f6her und h\u00f6her dann haben wir Jahrzehnts Zinseszins auch noch,<br \/>[00:17:15] das ist dann der zweite Fehler also zwar im Moment ist es so vielleicht geht das ja schon Richtung Gradido also Moment ist ja der,<br \/>[00:17:25] zumindest mal der Leitzins um die Null schwankt um null teilweise auch mit Negativzinsen.<br \/>[00:17:32] Das w\u00e4re unter bestimmten Umst\u00e4nden auch ganz gut also wenn man wirklich ein Kreislauf von Werden und Vergehen schaffen w\u00fcrden.<br \/>[00:17:40] Allerdings gibt es auch andere vermehrungs Mechanismen die die Zins und Zinseszins halt mit dem anderen Namen funktionieren es f\u00fchrt dazu,<br \/>[00:17:49] dass die Verm\u00f6gen auch noch exponential wachsen logischerweise wachsen dann auch die Schulden exponential nur III Fehler ist eben die Summe aus beiden n\u00e4mlichen dass die Naturgesetze,<br \/>[00:18:02] missachtet werden<br \/>[00:18:03] das wichtigste Naturgesetz ist das Gesetz von Bern und Vergehen von dem wir eben gesprochen haben wir w\u00fcrden noch weitere Naturgesetze finden oder meiner sie jetzt hier in der Wirtschaft Bionik weiter forscht<br \/>[00:18:15] dann kommt man auf weitere Punkte aber das Wesentliche ist eigentlich dass sie da Kreislauf von Werden und Vergehen,<br \/>[00:18:21] den wir ja auch schon im Volksmund den Kreislauf des Lebens nennen das hei\u00dft also,<br \/>[00:18:27] das ist uns ja als Menschen bewusst dass es ein Kreislauf gibt auch wir Menschen sind verg\u00e4nglich m\u00f6gen es zwar nicht gerne dass wir verg\u00e4nglich sind aber es ist normal so und damit sorgt die Natur,<br \/>[00:18:38] das eben auch.<br \/>[00:18:40] Von allem die richtige Menge da es ist hei\u00df es wird erschaffen also wir werden geboren und wir Vergehen wieder und wenn alles im Gleichgewicht ist,<br \/>[00:18:49] dann ist auch \u00fcber die richtige Menge an Pflanzen und Tieren an Menschen und so weiter da sein sich selbstregulierendes System und das wird eben auch ein Geldsystem komplett vernachl\u00e4ssigt.<br \/>[00:19:02] Dann nichts kann auf einen begrenzten Raum st\u00e4ndig wachsen irgendwas w\u00e4re jetzt sp\u00fcren ist eigentlich krank ist Geld in einer.<br \/>[00:19:12] Krankengeld und ziehe m\u00fcsste ja eigentlich sein gesundes Geld f\u00fcr eine gesunde Welt Bernd genau das ist ja auch unser Wahlspruch gesundes Geld f\u00fcr eine gesunde Welt wir haben das Potenzial,<br \/>[00:19:26] Gesundheit zu schaffen indem man die Krankheit abschaffen Gespr\u00e4che zum Wirtschaftsbereich was im \u00fcbrigen auch dazu f\u00fchren wird das auch.<br \/>[00:19:37] Unsere Krankheiten also auch menschliche Krankheiten abnehmen ich habe mal eine interessante Untersuchung geh\u00f6rt dass etwa 80% aller Krankheiten auf Existenzangst beruhen.<br \/>[00:19:51] Oder zumindest von Existenzangst stark beeinflusst werden das hei\u00dft also wenn der Existenzangst wegf\u00e4llt,<br \/>[00:19:58] dann wird ein Gro\u00dfteil der Krankheiten einfach auch was ich aufl\u00f6sen auf mit weil die Existenzangst f\u00fchrt ja auch dazu dass das Immunsystem geschw\u00e4cht wird richtig,<br \/>[00:20:10] Immunsystem wird geschw\u00e4cht<br \/>[00:20:12] war st\u00e4ndig Stress man das kennen wir ja also heutzutage ist ja schon Mode war das man sagt wie geht&#8217;s dir auch bin im Stress gibt positiver Stress aber das meiste ist eben negativer Stress der durch Angst durch Existenzangst verursacht wird.<br \/>[00:20:26] Und auch in der Natur ist es eine Balance also es gibt diesen positiver Stress.<br \/>[00:20:31] Der muss aber immer in Balance sein dass man auch Entspannungsphasen hat also Natur ist ebenso wenn ihr es eine Maus vor einer Katze wegrennt und Gesetz sind bald sie schaffst dann,<br \/>[00:20:44] wird sie sich hinterher ne ganze Weile ausruhen,<br \/>[00:20:47] k\u00f6nnen und m\u00fcssen und deshalb tr\u00e4gt eine Maus keinen Burnout jetzt oder auseinander ist ihr weil das normaler Kreislauf ist zwischen,<br \/>[00:20:56] kurzzeitstress die Sache ist schnell vorbei und danach kommt diese Erholungsphase und es ist auch wieder,<br \/>[00:21:04] schau mal wie einatmen ausatmen oder Kreislauf das ist immer sind immer die gleichen Prinzipien ja das ist Balance das ist einfach eine nat\u00fcrliche Person auf seine echte Lebensqualit\u00e4t.<br \/>[00:21:15] Eine Lebensqualit\u00e4t Stadt Leistungsdruck wie wir ihn kennen,<br \/>[00:21:20] genau statt Leistungsdruck also Leistungsanspruch ist eine sch\u00f6ne Sache sch\u00f6n ja nicht dass auch Sportler erleben d\u00fcrfen er auch da ist es so.<br \/>[00:21:31] Die Leistung konzentriert sich auf einen Moment gut dann wird noch H\u00f6chstleistung vollbracht,<br \/>[00:21:38] und danach ist wieder eine Entspannungsphase solange das gew\u00e4hrleistet ist dass ist eben im allgemeinen im Berufsleben nicht der Fall war da haben wir n\u00e4mlich im allgemeinen Dauerstress.<br \/>[00:21:50] Und da werden die Entspannungsphasen immer weniger das ist also sowas wie so ein latenter Stress und latente Existenzangst und daf\u00fcr ist die Natur nicht gebaut weil sowas gibt&#8217;s in der Natur Natur gibt&#8217;s keine Existenz.<br \/>[00:22:03] Sie haben dieses Grundeinkommen.<br \/>[00:22:09] Was ist denn wenn man aus gesundheitlichen oder altersbedingten Gr\u00fcnden zum Gemeinwohl nicht mehr beitragen kann was passiert mit.<br \/>[00:22:18] Den Menschen.<br \/>[00:22:20] Und grunds\u00e4tzlich meinte fahren wir jetzt schon so wenn ein Mensch aus gesundheitlichen Gr\u00fcnden nicht zur Gemeinschaft beitragen kann also das ist,<br \/>[00:22:29] jetzt schon so dass man ja dann,<br \/>[00:22:32] eine Versorgung gibt gelesen Absicherung soziale Absicherung leben ja in einem Sozialstaat das wird nat\u00fcrlich bei Gradido oder ein Gradido Modell weiterhin bestehen.<br \/>[00:22:44] Allerdings es gibt ein erweiterten Gedanken n\u00e4mlich,<br \/>[00:22:47] du brauchst doch an wenn einer aus Altersgr\u00fcnden z.b. nicht beitragen kann jetzt ist die Frage was hei\u00dft beitragen also es gibt alte Menschen die tragen liebend gerne auf ihrer Art und Weise bei.<br \/>[00:23:00] Also ein alter Mann kann z.b. ja da kann seine Lebenserfahrung an junge Menschen weitergeben,<br \/>[00:23:06] ja oder sie braucht ihr jetzt nicht mehr schnell und viel zu arbeiten sich um die Enkelkinder k\u00fcmmern,<br \/>[00:23:12] man kann sich um die Enkelkinder k\u00fcmmern die Enkelkinder sind total dankbar wenn Oma und Opa um sich herum sind das hei\u00dft also es gibt viele M\u00f6glichkeiten wo auch alte Menschen beitragen k\u00f6nnen.<br \/>[00:23:25] Ohne aber dabei jetzt in einen Leistungsdruck kommen zu m\u00fcssen und es interessante ist das,<br \/>[00:23:32] gerade alte Menschen auch da gibt&#8217;s wieder Untersuchung wenn man direkt aus seinem Berufsleben unvorbereitet in die Pensionierung kommt,<br \/>[00:23:42] dann gibt viele Menschen die krank werden.<br \/>[00:23:44] Weil die auf einmal keine Aufgabe mehr haben und damit nicht umgehen k\u00f6nnen deshalb r\u00e4t man ja auch dass man sich vorbereitet auf den Ruhestand und sich dann entsprechende Aufgaben im Vorfeld schon raus sucht,<br \/>[00:23:58] und genau das wird erleichtert durch aktive Grundeinkommen indem man sicher anbringen kann in die Gemeinschaft und die Gemeinschaft auch f\u00f6rdert und zwar eingeben Alter nat\u00fcrlich wenn einer nicht mehr,<br \/>[00:24:09] kann es ganz klar dass die Versorgung immer gew\u00e4hrleistet ist wie wird denn das Geld verteilt.<br \/>[00:24:17] Der Gradido oder das aktive Grundeinkommen generell wie kommt es an bei den Menschen,<br \/>[00:24:25] General ist das ein Vorgang Mann gibt also innerhalb einer Gemeinschaft das kann also z.b. so einer,<br \/>[00:24:32] ja wenn der Dorfgemeinschaft k\u00f6nnte das sein und nat\u00fcrlich nach Stadtteilen oder so man gibt an was mache ich in der Gemeinschaft vielleicht gibt&#8217;s da auch sowas wie eine Gemeinschaftsschule wo man bespricht was gibt es denn f\u00fcr Dinge,<br \/>[00:24:46] die getan werden sollten.<br \/>[00:24:49] Und schaut wer kann und wer macht das gerne Haus man kann das durchaus verteilt und sobald da jemand etwas getan hat f\u00fcr die Gemeinschaft dann wird es von Vertrauenspersonen best\u00e4tigt.<br \/>[00:25:02] Und in dem Moment von einem Konto also B\u00e4r das Geld nun sch\u00f6pft ob das nun das ehemalige Finanzamt ist oder ob dass das Einwohnermeldeamt ist oder einen speziell daf\u00fcr geschaffen es Abend ist.<br \/>[00:25:13] Oder ob es die Zentralbank ist es ist letztendlich ja nur ein rein administrativer Vorgang wichtig ist man bringt sich ein.<br \/>[00:25:22] Und dokumentiert was mache ich f\u00fcr die Gemeinschaft parallel kommt dieser Sch\u00f6pfungsprozess das Geld wird als Guthaben Gesch\u00e4ft bei Gradido ist \u00fcber ist ganz wichtig es werden keine Schulden daf\u00fcr gesch\u00f6pft.<br \/>[00:25:33] Bei Gradido gibt es nur Guthaben Sch\u00f6pfung es gibt also es gibt ja auch keine Steuern es gibt keine Steuern richtig ne das ist das n\u00e4chste.<br \/>[00:25:43] Weil wir haben n\u00e4mlich eine dreifache Geldsch\u00f6pfung konzipiert also 3 x 1000 Gradido werden f\u00fcr jeden Menschen im Monat Gesch\u00e4ft entspricht etwa 3000 \u20ac entspricht etwa 3000 \u20ac.<br \/>[00:25:56] Und die ersten 1000 sind wie gesagt uns aktive Grundeinkommen die zweiten f\u00fcr.<br \/>[00:26:02] Staatshaushalt wir k\u00f6nnten auch sagen Gemeinschaftshaus halt dann wir Menschen leben in Gemeinschaften,<br \/>[00:26:09] wie auch immer sich die Gemeinschaften jetzt entwickeln im Moment haben wir L\u00e4nder starten und so weiter es kann sich aber auch mal anders entwickelt und III und ganz wesentlicher Punkt ist der Ausgleichs und<br \/>[00:26:20] umweltfond noch mal in derselben H\u00f6he wie der Staatshaushalt.<br \/>[00:26:25] Der dient wie der Name schon sagt eben zur Sanierung der Umwelt,<br \/>[00:26:31] kann daf\u00fcr verwendet werden das Getriebe umstellen auf biologische Produktion dann kann,<br \/>[00:26:39] benutzt werden das \u00fcberf\u00e4llige Sanierung gesund BB<br \/>[00:26:44] die Meere die sind ja im Moment voll von Plastik das man also hier ganz bewusst auch die Meere s\u00e4ubert oder dass man die Regenw\u00e4lder wieder auf hosted und und und.<br \/>[00:26:54] Denn der Auslastung Umwelt vor ist so hoch wie der Staatshaushalt und dann alle L\u00e4nder mitmachen ist er so hoch wie alle Staatshaushalte der Welt zusammen und spreche von der H\u00f6he eine Staatshaushalt ist zu etwa wie wir ihn in Deutschland kennen.<br \/>[00:27:09] Was ist denn dann das Wesen des Gradido also f\u00fcr mich ist es eigentlich eine friedliche Transformation des Geldsystems,<br \/>[00:27:19] kann man so sagen also es geht wirklich um eine friedliche Transformation dampfs\u00e4g ein sanfter weg er kann auch parallel sanft eingef\u00fchrt werden,<br \/>[00:27:29] muss ans jetzt nicht ein dich doch geben wo man sagt ab morgen ist Gradido soll man kann,<br \/>[00:27:33] anfangen ganz sanft mit 10% Gradido Anteil und dann ja sp\u00e4ter mal den 20% und so weiter so dass wir uns daran gew\u00f6hnen k\u00f6nnen und sanft,<br \/>[00:27:44] das neue einf\u00fcgen das kann ja sowohl Bargeld sein als auch digitales Geld,<br \/>[00:27:49] also es funktioniert mit jedem Zahlungsmittel digitales Geld ist vergleichsweise heutzutage einfach herzustellen wir haben auch Modell f\u00fcr Bargeld,<br \/>[00:27:58] wobei wenn man jetzt so sieht wie die Tendenz ist wird ja Bargeld immer an Bedeutung verlieren von der Seite von Gradido ist beides m\u00f6glich.<br \/>[00:28:09] Lass uns noch mal ganz kurz zu eurer Akademie kommen.<br \/>[00:28:16] Es handelt sich um ein freies internationales Forschungsnetzwerk.<br \/>[00:28:23] Wir sind ja so vernetzt in 12 die Welt ist ein Dorf geworden also wir haben Menschen wachsen zusammen L\u00f6sungen dieser Gr\u00f6\u00dfenordnung sollten wirklich auch international angestrebt werden,<br \/>[00:28:34] auch wenn Kathi du so konzipiert ist das auch einzelne L\u00e4nder zun\u00e4chst mal sanft anfangen k\u00f6nnen,<br \/>[00:28:41] dann man kann ich von ausgehen dass du fort sich alle L\u00e4nder da anschlie\u00dfend man kann in einzelne anfangen.<br \/>[00:28:47] Das Forschungsnetzwerk ist international und Webseite ist in allen Sprachen z.b. alles geht einfach darum dass wir jetzt die L\u00f6sung in die Welt bringen jetzt wo es die Welt so dringend braucht.<br \/>[00:29:01] Tja wie sieht es aus bei den Reichsten der Reichen wenn die jetzt quasi also die Milliard\u00e4re die billion\u00e4re davon h\u00f6ren k\u00f6nnen die \u00fcberhaupt was mit Gradido.<br \/>[00:29:14] Anfangen haben Sie gegebenenfalls sogar einen Nutzen wenn Sie mitmachen ja k\u00f6nnte ich mir schon vorstellen dass sie sagen.<br \/>[00:29:23] Ich muss eigentlich keine Angst haben dass ich mein Verm\u00f6gen verliere ganz im Gegenteil ich kann etwas Gutes tun.<br \/>[00:29:31] Das ist ja gerade bei psychisch gesunden Menschen die wollen ja was Gutes tun also erstmal unabh\u00e4ngig vom Reichtum den man nur hat.<br \/>[00:29:40] Oder auch nicht hat also das Bed\u00fcrfnis etwas Gutes zu tun haben alle Menschen und von daher gehen wir davon aus da ja niemanden Nachteil hat,<br \/>[00:29:49] also auch die reichen Menschen haben keinen Nachteil in den Sinn davon gut die haben vielleicht etwas weniger macht aber macht es nicht unbedingt Lebensqualit\u00e4t.<br \/>[00:30:00] Wenn es um Lebensqualit\u00e4t geht wir haben mehr Sicherheit zum Beispiel also heutzutage gibt es ja wirklich auch reichen Ghettos,<br \/>[00:30:08] wo die Kinder mit Bodyguards in die Schule gebracht werden m\u00fcssen einfach weil die so gef\u00e4hrlich leben um sich diesmal vorstellt in dem Moment wo es keine Armut mehr gibt.<br \/>[00:30:18] Dann ist das Aggressionspotenzial der Menschen ja nahezu null man es allen Menschen gut geht.<br \/>[00:30:24] Dann gibt&#8217;s vielleicht noch ein paar wenige die krankhaft kriminell sind aber diese Armut bedingte Kriminalit\u00e4t die ja zu mafi\u00f6sen Strukturen und allen m\u00f6glichen.<br \/>[00:30:33] \u00dcben Endingen f\u00fchrt nat\u00fcrlich auch zu kriegen.<br \/>[00:30:36] Die f\u00e4llt weg in dem Moment wo alle Menschen wohlhabend sind also in einem gesunden Ma\u00dfe wohlhabend und das kommt auch den reichen Menschen zugute.<br \/>[00:30:47] Es hei\u00dft ja also so wie ich es eben auch verstanden habe das Gradido \u00fcber das Jahr seinen Wert etwa um 50% verliert,<br \/>[00:30:58] jetzt k\u00f6nnte mal zun\u00e4chst ja mal sagen ja Moment jetzt verlier ich ja die H\u00e4lfte meines Verm\u00f6gens nicht was macht man mit seinem Verm\u00f6gen wenn es eigentlich.<br \/>[00:31:07] Um die H\u00e4lfte halbiert wird im Jahr ja also,<br \/>[00:31:12] es wird also die H\u00e4lfte \u00e4hnlich wie beim Negativzins wird im Hintergrund abgebucht also kontinuierlich jetzt nicht zum bestimmten Stichtag sonst wird immer ein klein bisschen abgebucht dann kann sich das vorstellen so \u00e4hnlich in Negativzins.<br \/>[00:31:27] Ja was macht man dann.<br \/>[00:31:29] Nur noch mach das was man nicht tun sollte mit Geld n\u00e4mlich erst dort einzusetzen wo es gebraucht wird in der Praxis hei\u00dft das,<br \/>[00:31:38] man gibt z.b. credit an jemand der gerade im Moment ein Projektplan das Projekt kann auch sein dass ein Projekt keine eigene Firma sein es kann sein dass jemand oder gerade Geld braucht weil ich eine Auszeit,<br \/>[00:31:51] g\u00f6nnen will also die Lebensplan Gestaltung wird immer flexibler als gibt viele Gr\u00fcnde wo man anderen Menschen helfen kann mit einem Kredit,<br \/>[00:32:01] und derjenige wird dann zum vereinbarten Zeitpunkt dann das Geld wieder zur\u00fcckzahlen oder in Raten oder wie auch immer es eben vereinbart ist,<br \/>[00:32:09] das k\u00f6nnen dann auch Finanzinstitute die Vermittlung machen und die Sache auch absichern mit Ausfallversicherung was ist da immer ansprechenden Vertr\u00e4ge nat\u00fcrlich.<br \/>[00:32:20] Und das hei\u00dft eben auch bez\u00fcglich des aktiven Grundeinkommens.<br \/>[00:32:25] Ich kann ja auch ganz was anderes machen wenn ich mehr Geld verdienen m\u00f6chte dann mache ich das eben dann verst\u00e4ndlich also das aktive Grundeinkommen ist ein Sockel.<br \/>[00:32:33] Es ist erstens ist es freiwillig oder du musst es nicht machen.<br \/>[00:32:37] Darfst du helfen also jeder Mensch hat das Recht wenn du aber jetzt etwas anderes machst beruflich und m\u00f6glicherweise wesentlich mehr Verdienst als 20 Gradido die Stunde,<br \/>[00:32:48] aber vielleicht sagen ja gut ich habe jetzt keine Zeit f\u00fcr das aktive Grundeinkommen es kann aber auch als Sockel dienen und dann kannst du in der restlichen Zeit also 50 Stunden im Monat ungef\u00e4hr zwei Stunden.<br \/>[00:33:02] Tag und restlichen Zeit kannst du zus\u00e4tzlich ja machen was du willst und das Sch\u00f6ne ist,<br \/>[00:33:08] es ist steuerfrei also jeglicher Art von beruflicher Arbeit ist steuerfrei das hei\u00dft das was du f\u00fcr dich erwirtschaftete,<br \/>[00:33:16] das hast du dann auch und du musst aber auch nicht gro\u00df Buchhaltung auf da weniger Stress weniger Stress weniger Druck weniger B\u00fcrokratie,<br \/>[00:33:25] Und wenn man sich mal so vor steht eine vierk\u00f6pfige Familie hat jeden Monat 4000 Gradido.<br \/>[00:33:34] Steuerfrei,<br \/>[00:33:35] richtig also im Forum vom aktiven Grundeinkommen f\u00fcr alle wenn alle vier jetzt sich an der bedingungslosen Teilhabe beteiligt und es k\u00f6nnen nat\u00fcrlich auch Kinder machen auf kindgerechte Art und Weise selbstverst\u00e4ndlich dann haben die,<br \/>[00:33:49] 4000 Gradido im Wert von 4000 \u20ac und die Eltern k\u00f6nnen \u00fcber die wollen auch noch gesch\u00e4ftlich oder beruflich t\u00e4tig sein.<br \/>[00:34:00] Dabei kommen wir noch mal zum Anfang zur\u00fcck vor \u00fcber 20 Jahren ja.<br \/>[00:34:07] Du hast in diesem zwei Jahrzehnten ihr habt ihn sind zwei Jahrzehnten.<br \/>[00:34:13] Unglaublich viel erlebt ich kann mir vorstellen am Anfang seid ihr sehr bel\u00e4chelt worden.<br \/>[00:34:21] In Zeiten der Corona Krise denke ich werdet ihr mit diese Gradido Akademie f\u00fcr ernst genommen.<br \/>[00:34:29] Ja das ist eine sch\u00f6ne Entwicklung also wir k\u00f6nnen jetzt erleben als es ging eigentlich schon vor der Corona Krise in Rust in den ersten Jahren wie du sagtest worden wir bel\u00e4chelt vielleicht war das auch ein Schutz ich mal auf der einen Seite.<br \/>[00:34:43] D\u00fcrfen wir uns menschlich entwickeln wir durften das Gradido Modell ja immer mehr verfeinern.<br \/>[00:34:51] Und wenn man mit so ungewohnten Ideen kommt.<br \/>[00:34:54] Und zu schnell gro\u00df wird dann kann man auch sehr schnell dann man wegen angegriffen werden oder in Schubladen gesteckt werden das alles braucht eine Zeit.<br \/>[00:35:05] Es ist eine solide Entwicklung gewesen mal 20 Jahre ist eine lange Zeit gab auch gro\u00dfe Durststrecken im Nachhinein muss ich sagen ich bin total dankbar und ich denke auch Margit sieht zwar das aus ersten vier beide.<br \/>[00:35:20] Wirklich die Zeit hatten intensiv zu verarschen und forschen hei\u00dft auch in dem Fall immer wieder zu hinterfragen.<br \/>[00:35:27] Also nicht nur weil man es manchmal hatte tolle Idee jetzt sich in die eigene Idee zu verlieben war immer wieder hinterfragen stimmt es eigentlich kann das sein kannst funktionieren also inzwischen haben wir \u00fcber,<br \/>[00:35:38] 100 m\u00f6gliche Vorteile von Gradido herausarbeiten d\u00fcrfen oder gesehen haben eigentlich in jeder,<br \/>[00:35:45] Lebenssituation und jeder wirtschaftlichen Situation haben alle einen Vorteil,<br \/>[00:35:51] unser Haupt ethische Grundlage ist ja das Dreifache wohl das hei\u00dft also alles was entschieden was alles was getan wird im Rahmen der nat\u00fcrlichen \u00d6konomie des Lebens,<br \/>[00:36:01] muss dem Wohl des einzelnen dienen wohl des Einzelnen,<br \/>[00:36:05] wir haben du und ich also nicht nur ich sondern wir beide da h\u00f6rt sie ja schon der Wirtschaft auf also in der Wirtschaft ist mal ja schon ganz froh wenn es Win-Win-Situation gibt also wenn es beiden Teilen gut geht,<br \/>[00:36:18] aber II wo ist es wohl der Gemeinschaft es muss also auch der Gemeinschaft gut gehen.<br \/>[00:36:23] Und im auf dem gro\u00dfen Ganzen kann man sagen der Natur.<br \/>[00:36:28] Denn das macht nicht Sinn dass wir im Gesch\u00e4ft miteinander machen wo wir letztendlich den Ast abs\u00e4gen auf dem der sitzen in dem der eben gegen die Natur arbeiten.<br \/>[00:36:39] Und von daher ist es wirklich WINWIN also man kann sagen Multivan oder omni Winden omni wenn ja Gewinn und mittlerweile gibt es ja auch schon 4000 F\u00f6rderer Mitglieder,<br \/>[00:36:52] die der Idee folgen lassen es ist sogar mehr geworden und es werden auch dann nicht mehr und das freut uns nat\u00fcrlich riesig.<br \/>[00:37:01] Das Candido Netzwerk w\u00e4chst und.<br \/>[00:37:04] Ja die Menschen wenn es einmal verstanden haben erz\u00e4hlen wirklich mit Freude weiter und so,<br \/>[00:37:11] verbreitet sich als Gradido man kann fast sagen welchen hat Zeit wie jetzt wie ein positiver gl\u00fccksvirus und da freuen wir uns riesig dr\u00fcber.<br \/>[00:37:21] Lieber Bernd ganz herzlichen Dank ich danke f\u00fcr diese Podcast Premiere und deiner einf\u00fchren.<br \/>[00:37:30] In das Thema Gradido die nat\u00fcrliche \u00d6konomie des Lebens.<br \/>[00:37:35] Als n\u00e4chstes werden wir uns dem Thema K\u00fcnstler und Journalisten widmen.<br \/>[00:37:42] Die Garage in dieser weltweiten Corona Krise besonders hart betroffen sind wie viele andere auch.<br \/>[00:37:52] Daher werden wir uns f\u00fcr unsere Podcast ja immer ganz aktuelle Themen aus allen gesellschaftlichen Bereichen herausgreifen.<br \/>[00:38:01] Um dann mit prominenten Experten l\u00f6sungsorientierte Antworten aus der Gradido Akademie vorzustellen.<br \/>[00:38:10] Wer mehr \u00fcber Gradido erfahren m\u00f6chte schaut am besten.<br \/>[00:38:16] Auf die Internetseite www.grado.it.<br \/>[00:38:21] Die sich mittlerweile du hast es schon gesagt in sage und schreibe 11 Sprachen prezenty.<br \/>[00:38:30] Hier gibt es auch nat\u00fcrlich die M\u00f6glichkeit sich \u00fcber eine Mitgliedschaft oder F\u00f6rderungsm\u00f6glichkeiten einzubringen.<br \/>[00:38:38] Immerw\u00e4hrend ganz herzlichen Dank das ist ja unglaublich.<br \/>[00:38:43] Was die Akademie auf die Beine gestellt hat gerade zur rechten Zeit.<br \/>[00:38:51] Bleibt uns beiden noch allen Gradido Mitstreitern weiterhin frohes Schaffen zu w\u00fcnschen f\u00fcr.<br \/>[00:38:59] Ein gesundes Geld in einer gesunden Welt bis bald Michael.<br \/>[00:39:06] Music.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Neue Wege in eine bessere Welt \u2013 Die Corona-Krise zwingt uns zur Besinnung auf das Wesentliche und birgt gleichzeitig die Chance zu einem Neubeginn. Gemeinsam brechen wir auf in eine neue Zeit, in der wir, unsere Kinder und alle Kinder der Welt in Frieden und Wohlstand leben k\u00f6nnen \u2013 im Einklang mit der Natur. [39:20]<\/p>\n","protected":false},"author":2,"featured_media":1563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff - Gradido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gradido.net\/bg\/episode-1\/\" \/>\n<meta property=\"og:locale\" content=\"bg_BG\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff - Gradido\" \/>\n<meta property=\"og:description\" content=\"Neue Wege in eine bessere Welt \u2013 Die Corona-Krise zwingt uns zur Besinnung auf das Wesentliche und birgt gleichzeitig die Chance zu einem Neubeginn. Gemeinsam brechen wir auf in eine neue Zeit, in der wir, unsere Kinder und alle Kinder der Welt in Frieden und Wohlstand leben k\u00f6nnen \u2013 im Einklang mit der Natur. [39:20]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gradido.net\/bg\/episode-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradido\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-13T09:58:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T16:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1221\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bernd H\u00fcckst\u00e4dt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bernd H\u00fcckst\u00e4dt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 \u043c\u0438\u043d\u0443\u0442\u0438\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/\"},\"author\":{\"name\":\"Bernd H\u00fcckst\u00e4dt\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/person\\\/9c503a004ad15a1ddecadce2218db5d1\"},\"headline\":\"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff\",\"datePublished\":\"2020-12-13T09:58:18+00:00\",\"dateModified\":\"2021-06-07T16:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/\"},\"wordCount\":5613,\"publisher\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/podcast_www_premiere.jpg\",\"articleSection\":[\"Podcast\"],\"inLanguage\":\"bg-BG\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/\",\"name\":\"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff - Gradido\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/podcast_www_premiere.jpg\",\"datePublished\":\"2020-12-13T09:58:18+00:00\",\"dateModified\":\"2021-06-07T16:54:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#breadcrumb\"},\"inLanguage\":\"bg-BG\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"bg-BG\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/podcast_www_premiere.jpg\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/podcast_www_premiere.jpg\",\"width\":1800,\"height\":1221},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gradido.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"name\":\"Gradido\",\"description\":\"Die neue W\u00e4hrung hei\u00dft Dankbarkeit\",\"publisher\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gradido.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bg-BG\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\",\"name\":\"Gradido\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bg-BG\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"width\":527,\"height\":273,\"caption\":\"Gradido\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/person\\\/9c503a004ad15a1ddecadce2218db5d1\",\"name\":\"Bernd H\u00fcckst\u00e4dt\",\"sameAs\":[\"https:\\\/\\\/gradido.net\"],\"url\":\"https:\\\/\\\/gradido.net\\\/bg\\\/author\\\/bernd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041f\u043e\u0434\u043a\u0430\u0441\u0442\u044a\u0442 Gradido \u0437\u0430\u043f\u043e\u0447\u0432\u0430 \u0441 \u0432\u044a\u043b\u043d\u0435\u043d\u0438\u0435, \u043d\u0430\u0434\u0435\u0436\u0434\u0430 \u0438 \u0434\u0438\u043d\u0430\u043c\u0438\u0442 - Gradido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gradido.net\/bg\/episode-1\/","og_locale":"bg_BG","og_type":"article","og_title":"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff - Gradido","og_description":"Neue Wege in eine bessere Welt \u2013 Die Corona-Krise zwingt uns zur Besinnung auf das Wesentliche und birgt gleichzeitig die Chance zu einem Neubeginn. Gemeinsam brechen wir auf in eine neue Zeit, in der wir, unsere Kinder und alle Kinder der Welt in Frieden und Wohlstand leben k\u00f6nnen \u2013 im Einklang mit der Natur. [39:20]","og_url":"https:\/\/gradido.net\/bg\/episode-1\/","og_site_name":"Gradido","article_published_time":"2020-12-13T09:58:18+00:00","article_modified_time":"2021-06-07T16:54:29+00:00","og_image":[{"width":1800,"height":1221,"url":"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg","type":"image\/jpeg"}],"author":"Bernd H\u00fcckst\u00e4dt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bernd H\u00fcckst\u00e4dt","Est. reading time":"28 \u043c\u0438\u043d\u0443\u0442\u0438"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gradido.net\/tr\/episode-1\/#article","isPartOf":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/"},"author":{"name":"Bernd H\u00fcckst\u00e4dt","@id":"https:\/\/gradido.net\/de\/#\/schema\/person\/9c503a004ad15a1ddecadce2218db5d1"},"headline":"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff","datePublished":"2020-12-13T09:58:18+00:00","dateModified":"2021-06-07T16:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/"},"wordCount":5613,"publisher":{"@id":"https:\/\/gradido.net\/de\/#organization"},"image":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/#primaryimage"},"thumbnailUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg","articleSection":["Podcast"],"inLanguage":"bg-BG"},{"@type":"WebPage","@id":"https:\/\/gradido.net\/tr\/episode-1\/","url":"https:\/\/gradido.net\/tr\/episode-1\/","name":"\u041f\u043e\u0434\u043a\u0430\u0441\u0442\u044a\u0442 Gradido \u0437\u0430\u043f\u043e\u0447\u0432\u0430 \u0441 \u0432\u044a\u043b\u043d\u0435\u043d\u0438\u0435, \u043d\u0430\u0434\u0435\u0436\u0434\u0430 \u0438 \u0434\u0438\u043d\u0430\u043c\u0438\u0442 - Gradido","isPartOf":{"@id":"https:\/\/gradido.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/#primaryimage"},"image":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/#primaryimage"},"thumbnailUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg","datePublished":"2020-12-13T09:58:18+00:00","dateModified":"2021-06-07T16:54:29+00:00","breadcrumb":{"@id":"https:\/\/gradido.net\/tr\/episode-1\/#breadcrumb"},"inLanguage":"bg-BG","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gradido.net\/tr\/episode-1\/"]}]},{"@type":"ImageObject","inLanguage":"bg-BG","@id":"https:\/\/gradido.net\/tr\/episode-1\/#primaryimage","url":"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2020\/12\/podcast_www_premiere.jpg","width":1800,"height":1221},{"@type":"BreadcrumbList","@id":"https:\/\/gradido.net\/tr\/episode-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gradido.net\/"},{"@type":"ListItem","position":2,"name":"Gradido-Podcast startet mit Spannung, Hoffnung und Z\u00fcndstoff"}]},{"@type":"WebSite","@id":"https:\/\/gradido.net\/de\/#website","url":"https:\/\/gradido.net\/de\/","name":"Gradido","description":"\u041d\u043e\u0432\u0430\u0442\u0430 \u0432\u0430\u043b\u0443\u0442\u0430 \u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u043d\u043e\u0441\u0442","publisher":{"@id":"https:\/\/gradido.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gradido.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bg-BG"},{"@type":"Organization","@id":"https:\/\/gradido.net\/de\/#organization","name":"Gradido","url":"https:\/\/gradido.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"bg-BG","@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","width":527,"height":273,"caption":"Gradido"},"image":{"@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gradido.net\/de\/#\/schema\/person\/9c503a004ad15a1ddecadce2218db5d1","name":"\u0411\u0435\u0440\u043d\u0434 \u0425\u044e\u043a\u0449\u0430\u0434\u0442","sameAs":["https:\/\/gradido.net"],"url":"https:\/\/gradido.net\/bg\/author\/bernd\/"}]}},"_links":{"self":[{"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/posts\/1110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/comments?post=1110"}],"version-history":[{"count":72,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/posts\/1110\/revisions"}],"predecessor-version":[{"id":2758,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/posts\/1110\/revisions\/2758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/media\/1563"}],"wp:attachment":[{"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/media?parent=1110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/categories?post=1110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gradido.net\/bg\/wp-json\/wp\/v2\/tags?post=1110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}