{"id":2118,"date":"2021-03-30T22:36:45","date_gmt":"2021-03-30T20:36:45","guid":{"rendered":"https:\/\/gradido.net\/?page_id=2118"},"modified":"2025-11-19T09:24:22","modified_gmt":"2025-11-19T08:24:22","slug":"what-is-gradido","status":"publish","type":"page","link":"https:\/\/gradido.net\/fi\/what-is-gradido\/","title":{"rendered":"Hyvinvointi"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2118\" class=\"elementor elementor-2118\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a4b523 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1a4b523\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5be94b9\" data-id=\"5be94b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0569be elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"b0569be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9c6de27 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"what-is-gradido\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9284be7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9284be7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32b5b97\" data-id=\"32b5b97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fc4979 elementor-widget elementor-widget-heading\" data-id=\"6fc4979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Gradido-tutkimushanke - vaurautta ja rauhaa ihmiskunnan perheelle<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-818edde elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"818edde\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0e6e7d2\" data-id=\"0e6e7d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8c1955 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"c8c1955\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Hyvinvointitutkimus\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-c8c1955\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12050\"><a class=\"elementor-item\">Raha- ja talousj\u00e4rjestelm\u00e4<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12640\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vergleich-der-waehrungssysteme\/\" class=\"elementor-sub-item\">Valuuttaj\u00e4rjestelmien vertailu<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12047\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/economic-bionics\/\" class=\"elementor-sub-item\">Business bioniikka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12046\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/financial-system\/\" class=\"elementor-sub-item\">Rahoitusj\u00e4rjestelm\u00e4n kohtalokkaat puutteet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12049\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/basic-income\/\" class=\"elementor-sub-item\">Perustulo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12052\"><a class=\"elementor-item\">Visio 2050<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12583\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vision-2050\/\" class=\"elementor-sub-item\">Visio 2050<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12051\"><a class=\"elementor-item\">Yhteisty\u00f6<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12048\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/greatcooperation\/\" class=\"elementor-sub-item\">Suuri yhteisty\u00f6<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Valikko Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-c8c1955\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12050\"><a class=\"elementor-item\" tabindex=\"-1\">Raha- ja talousj\u00e4rjestelm\u00e4<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12640\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vergleich-der-waehrungssysteme\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Valuuttaj\u00e4rjestelmien vertailu<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12047\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/economic-bionics\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Business bioniikka<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12046\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/financial-system\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Rahoitusj\u00e4rjestelm\u00e4n kohtalokkaat puutteet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12049\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/basic-income\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Perustulo<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12052\"><a class=\"elementor-item\" tabindex=\"-1\">Visio 2050<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12583\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vision-2050\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Visio 2050<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-12051\"><a class=\"elementor-item\" tabindex=\"-1\">Yhteisty\u00f6<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-12048\"><a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/greatcooperation\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Suuri yhteisty\u00f6<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f125ef elementor-widget elementor-widget-breadcrumbs\" data-id=\"3f125ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/gradido.net\/fi\/\">Kotisivu<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1978f9 elementor-widget elementor-widget-text-editor\" data-id=\"e1978f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Millaisessa maailmassa lapsemme tulevat el\u00e4m\u00e4\u00e4n? <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/financial-system\/\">J\u00e4rjestelm\u00e4n vuoksi<\/a> rikkoo nykyisen <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/financial-system\/\">Rahoitusj\u00e4rjestelm\u00e4<\/a> juuri maailmanlaajuisesti, ja sit\u00e4 seuraa joukkomuutot, ty\u00f6tt\u00f6myys, k\u00f6yhyys ja sota.<\/p><p>Vain uuden, el\u00e4m\u00e4\u00e4n, rakkauteen ja my\u00f6t\u00e4tuntoon perustuvan rahaj\u00e4rjestelm\u00e4n avulla ihmiskunta voi selviyty\u00e4 n\u00e4ist\u00e4 haasteista kaikkien hyv\u00e4ksi. Gradido-akatemia <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/economic-bionics\/\">Business bioniikka<\/a> on kehitt\u00e4nyt kahdenkymmenen vuoden tutkimusty\u00f6n tuloksena t\u00e4llaisen j\u00e4rjestelm\u00e4n: Gradido, el\u00e4m\u00e4n luonnollinen talous, noudattaa luonnon miljardeja vuosia kest\u00e4neit\u00e4 menestysmalleja ja sill\u00e4 on potentiaalia lopettaa k\u00f6yhyys, n\u00e4lk\u00e4, sodat ja ymp\u00e4rist\u00f6n tuhoaminen. Yhdess\u00e4 luomme lapsenlapsille sopivan tulevaisuuden rauhassa ja sopusoinnussa luonnon kanssa.<\/p><p>Nimi \"Gradido\" tarkoittaa kiitollisuutta, arvokkuutta ja lahjoitusta. Gradido tekee mahdolliseksi kaikki ne hienot hankkeet ja aloitteet, jotka vanha rahoitusj\u00e4rjestelm\u00e4 oli aiemmin tukahduttanut. Eettinen perusta on yksil\u00f6n, yhteis\u00f6n ja suuremman kokonaisuuden kolminkertainen hyv\u00e4.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-778c947 elementor-widget elementor-widget-text-editor\" data-id=\"778c947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"color: #0b4034;\">Kolminkertainen rahanluonti l\u00e4pi el\u00e4m\u00e4n<\/h2><p>Toisin kuin <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/financial-system\/\">vanha maksuj\u00e4rjestelm\u00e4<\/a> Gradidossa rahan luominen tapahtuu jokaisen ihmisen toimesta:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fc2023\" data-id=\"2fc2023\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d126e1f elementor-widget elementor-widget-text-editor\" data-id=\"d126e1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Gradido<\/strong> =<br \/>Kiitollisuus - Kiitollisuus<br \/>Dignity - Arvokkuus<br \/>Lahjoitus - lahja<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5640661 elementor-widget elementor-widget-image\" data-id=\"5640661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png\" class=\"attachment-large size-large wp-image-2240\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png 1024w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480-300x188.png 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480-768x480.png 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480-16x10.png 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76bf098 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76bf098\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d961cb1\" data-id=\"d961cb1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b86e942 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b86e942\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-396612b\" data-id=\"396612b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-362260b elementor-widget elementor-widget-image\" data-id=\"362260b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/aktives-grundeinkommen.jpg\" class=\"attachment-large size-large wp-image-2134\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/aktives-grundeinkommen.jpg 800w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/aktives-grundeinkommen-300x188.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/aktives-grundeinkommen-768x480.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/aktives-grundeinkommen-16x10.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33fcbd6 elementor-widget elementor-widget-text-editor\" data-id=\"33fcbd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>1<br \/>Ehdottomaan osallistumiseen perustuva aktiivinen perustulo<\/h2><p>Jokaisella ihmisell\u00e4 on oikeus osallistua yhteis\u00f6n toimintaan omien taipumustensa ja kykyjens\u00e4 mukaisesti ja siten <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/basic-income\/\">Aktiivinen perustulo<\/a> 1 000 GDD (vastaa 1 000 euroa) kuukaudessa. Ihmiset, jotka saavat k\u00e4ytt\u00e4\u00e4 lahjojaan ja tuottaa hy\u00f6ty\u00e4, voivat kehitt\u00e4\u00e4 koko potentiaaliaan, saada siit\u00e4 iloa, vahvistaa hyvinvointiaan ja terveytt\u00e4\u00e4n. He ovat voimissaan ja voivat yhdess\u00e4 selviyty\u00e4 pienist\u00e4 ja suurista haasteista. Ehdoton osallistuminen on vapaaehtoista, perustulo on v\u00e4himm\u00e4ism\u00e4\u00e4r\u00e4. Lis\u00e4tulot ovat mahdollisia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b061bfb elementor-widget elementor-widget-image\" data-id=\"b061bfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/umweltfonds_768x480.jpg\" class=\"attachment-large size-large wp-image-2245\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/umweltfonds_768x480.jpg 1024w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/umweltfonds_768x480-300x188.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/umweltfonds_768x480-768x480.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/umweltfonds_768x480-16x10.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29015e4 elementor-widget elementor-widget-text-editor\" data-id=\"29015e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>3<br \/>Korvaus- ja ymp\u00e4rist\u00f6rahasto (AUF) pilaantuneiden alueiden kunnostamista varten.<\/h2><p>Kolmannet 1 000 GDD on varattu kauniin maapallomme palauttamiseen paratiisiksi, jollaiseksi se todenn\u00e4k\u00f6isesti aikoinaan oli tarkoitettu. Maailmanlaajuisesti k\u00e4ytt\u00f6\u00f6n otettu AUF on ylim\u00e4\u00e4r\u00e4inen ymp\u00e4rist\u00f6potti, joka vastaa kaikkia kansallisia talousarvioita yhteens\u00e4.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-760fa12\" data-id=\"760fa12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88725a7 elementor-widget elementor-widget-image\" data-id=\"88725a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/steuerfreier-staatshaushalt-fuer-jedes-land.jpg\" class=\"attachment-large size-large wp-image-2135\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/steuerfreier-staatshaushalt-fuer-jedes-land.jpg 800w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/steuerfreier-staatshaushalt-fuer-jedes-land-300x188.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/steuerfreier-staatshaushalt-fuer-jedes-land-768x480.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/03\/steuerfreier-staatshaushalt-fuer-jedes-land-16x10.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d371673 elementor-widget elementor-widget-text-editor\" data-id=\"d371673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>2<br \/>Veroton valtion talousarvio <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vision-2050\/\">jokainen maa<\/a><\/h2><p>Toinen rahanluonti 1 000 gdrd:n arvosta henke\u00e4 kohti kuukaudessa virtaa julkiseen budjettiin, joka on siis yht\u00e4 suuri kuin Saksassa t\u00e4ll\u00e4 hetkell\u00e4, mukaan lukien terveys- ja sosiaalipalvelut. Koska t\u00e4m\u00e4 tapahtuu jo rahan luomisen kautta, veroja, pakollisia vakuutuksia ja muita maksuja ei tarvita.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07e9205 elementor-widget elementor-widget-image\" data-id=\"07e9205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"502\" height=\"502\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/www_button__geldschoepfung.png\" class=\"attachment-large size-large wp-image-2246\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/www_button__geldschoepfung.png 502w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/www_button__geldschoepfung-300x300.png 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/www_button__geldschoepfung-150x150.png 150w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/www_button__geldschoepfung-12x12.png 12w\" sizes=\"(max-width: 502px) 100vw, 502px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3c61df elementor-widget elementor-widget-text-editor\" data-id=\"d3c61df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"color: #0b4034;\">Vakaa rahan tarjonta<br \/>luonnollinen kiertokulku<br \/>ja kulkee<\/h2><p>Kuukausittainen rahanluonti, joka on yhteens\u00e4 3 000 GDD henke\u00e4 kohti, yhdess\u00e4 5,6%:n jatkuvan kuukausittaisen perishabilityn (negatiivinen korko) kanssa muodostavat itses\u00e4\u00e4telyj\u00e4rjestelm\u00e4n, joka pit\u00e4\u00e4 rahan tarjonnan ja siten hinnat vakaina.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aabdcb2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aabdcb2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6fa0ec\" data-id=\"a6fa0ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2eb3044 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"2eb3044\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c39dde9\" data-id=\"c39dde9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed441ad elementor-widget elementor-widget-text-editor\" data-id=\"ed441ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"color: #0b4034;\">Lempe\u00e4 rauhanomainen muutos kaikkien hyv\u00e4ksi<\/h2><p>Gradido voidaan ottaa k\u00e4ytt\u00f6\u00f6n kaikkialla: yhteis\u00f6iss\u00e4, yksitt\u00e4isiss\u00e4 maissa ja\/tai maailmanlaajuisesti. Sen k\u00e4ytt\u00f6\u00f6notto voidaan toteuttaa vaiheittain rinnakkain vanhan j\u00e4rjestelm\u00e4n kanssa. T\u00e4m\u00e4 mahdollistaa <a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/vision-2050\/\">rauhanomainen muutos<\/a> ilman h\u00e4vi\u00e4ji\u00e4, joka hy\u00f6dytt\u00e4\u00e4 kaikkia ihmisi\u00e4 ja luontoa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcadc4f elementor-widget__width-auto muenze elementor-widget elementor-widget-image\" data-id=\"fcadc4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2020\/07\/Gradido-Coin_download.png\" class=\"attachment-full size-full wp-image-902\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2020\/07\/Gradido-Coin_download.png 500w, https:\/\/gradido.net\/wp-content\/uploads\/2020\/07\/Gradido-Coin_download-300x300.png 300w, https:\/\/gradido.net\/wp-content\/uploads\/2020\/07\/Gradido-Coin_download-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fcc3e0c\" data-id=\"fcc3e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fcd3c1 elementor-widget elementor-widget-image\" data-id=\"0fcd3c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/gemeinsam_geht_es_besser_768x480.jpg\" class=\"attachment-large size-large wp-image-2241\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/gemeinsam_geht_es_besser_768x480.jpg 1024w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/gemeinsam_geht_es_besser_768x480-300x188.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/gemeinsam_geht_es_besser_768x480-768x480.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/gemeinsam_geht_es_besser_768x480-16x10.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d438cd elementor-widget elementor-widget-text-editor\" data-id=\"9d438cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"color: #0b4034;\">Suuri yhteisty\u00f6 -<br \/>asiat ovat paremmin yhdess\u00e4<\/h2><p>Gradido perustuu luonnon plussumma-periaatteeseen, joka osoittaa meille, miten yhteisty\u00f6 (symbioosi) toimii. Siksi kutsumme teid\u00e4t mukaan\u201a<a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/greatcooperation\/\">Suuri yhteisty\u00f6<\/a>\u2018Kaikkien el\u00e4m\u00e4nmy\u00f6nteisten, positiivisten ihmisten, instituutioiden ja hankkeiden voimin. Yhdess\u00e4 luomme upean, el\u00e4m\u00e4narvoisen tulevaisuuden kaikille \u2013 lastemme ja heid\u00e4n lastensa vuoksi.<\/p><p>Tietoja Gradido-mallista, joka on\u201a<a href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/greatcooperation\/\">Suuri yhteisty\u00f6<\/a>\u2018 ja maailmanlaajuisesti maksuttomalla Gradido-tilill\u00e4 osoitteessa www.gradido.net<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ae5b5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ae5b5c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7986b09\" data-id=\"7986b09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7aa2f0 elementor-widget elementor-widget-heading\" data-id=\"f7aa2f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><strong>Sin\u00e4kin voit tukea<br><\/strong>rauhanomainen muutos paremman maailman puolesta:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3687857 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3687857\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-892f8c9\" data-id=\"892f8c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45bf39f elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"45bf39f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fi\/memberships\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Liity j\u00e4seneksi \/ sponsoriksi<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dc1baeb\" data-id=\"dc1baeb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fd4ce0 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"6fd4ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fi\/coin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Rekister\u00f6i Gradido-tili<br>Maailmanlaajuisesti ilmaiseksi!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-caecaaf\" data-id=\"caecaaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f689e0a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"f689e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elopage.com\/s\/gradido\/report\/payment?locale=de&#038;prid=111&#038;pid=%5Bgradido_pid%5D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pyyd\u00e4 tietoja<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Forschungsprojekt Gradido \u2013 Wohlstand und Frieden f\u00fcr die Menschheitsfamilie In welch einer Welt sollen unsere Kinder leben? Systembedingt bricht das derzeitige Finanzsystem gerade weltweit zusammen, begleitet von Massenpleiten, Arbeitslosigkeit, Armut und Krieg. Nur mit einem neuen, auf Leben, Liebe und Mitgef\u00fchl gr\u00fcndenden Geldsystem kann die Menschheit diese Herausforderungen zum Wohle aller meistern. Die Gradido-Akademie f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2118","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wohlstand - Gradido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gradido.net\/fi\/what-is-gradido\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wohlstand - Gradido\" \/>\n<meta property=\"og:description\" content=\"Forschungsprojekt Gradido \u2013 Wohlstand und Frieden f\u00fcr die Menschheitsfamilie In welch einer Welt sollen unsere Kinder leben? Systembedingt bricht das derzeitige Finanzsystem gerade weltweit zusammen, begleitet von Massenpleiten, Arbeitslosigkeit, Armut und Krieg. Nur mit einem neuen, auf Leben, Liebe und Mitgef\u00fchl gr\u00fcndenden Geldsystem kann die Menschheit diese Herausforderungen zum Wohle aller meistern. Die Gradido-Akademie f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gradido.net\/fi\/what-is-gradido\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradido\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T08:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/\",\"name\":\"Wohlstand - Gradido\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/kreislauf_768x480.png\",\"datePublished\":\"2021-03-30T20:36:45+00:00\",\"dateModified\":\"2025-11-19T08:24:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/kreislauf_768x480.png\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/kreislauf_768x480.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gradido.net\\\/what-is-gradido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gradido.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wohlstand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"name\":\"Gradido\",\"description\":\"Die neue W\u00e4hrung hei\u00dft Dankbarkeit\",\"publisher\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gradido.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\",\"name\":\"Gradido\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"width\":527,\"height\":273,\"caption\":\"Gradido\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hyvinvointi - Gradido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gradido.net\/fi\/what-is-gradido\/","og_locale":"fi_FI","og_type":"article","og_title":"Wohlstand - Gradido","og_description":"Forschungsprojekt Gradido \u2013 Wohlstand und Frieden f\u00fcr die Menschheitsfamilie In welch einer Welt sollen unsere Kinder leben? Systembedingt bricht das derzeitige Finanzsystem gerade weltweit zusammen, begleitet von Massenpleiten, Arbeitslosigkeit, Armut und Krieg. Nur mit einem neuen, auf Leben, Liebe und Mitgef\u00fchl gr\u00fcndenden Geldsystem kann die Menschheit diese Herausforderungen zum Wohle aller meistern. Die Gradido-Akademie f\u00fcr [&hellip;]","og_url":"https:\/\/gradido.net\/fi\/what-is-gradido\/","og_site_name":"Gradido","article_modified_time":"2025-11-19T08:24:22+00:00","og_image":[{"width":1024,"height":640,"url":"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"5 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gradido.net\/what-is-gradido\/","url":"https:\/\/gradido.net\/what-is-gradido\/","name":"Hyvinvointi - Gradido","isPartOf":{"@id":"https:\/\/gradido.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gradido.net\/what-is-gradido\/#primaryimage"},"image":{"@id":"https:\/\/gradido.net\/what-is-gradido\/#primaryimage"},"thumbnailUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png","datePublished":"2021-03-30T20:36:45+00:00","dateModified":"2025-11-19T08:24:22+00:00","breadcrumb":{"@id":"https:\/\/gradido.net\/what-is-gradido\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gradido.net\/what-is-gradido\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/gradido.net\/what-is-gradido\/#primaryimage","url":"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2021\/04\/kreislauf_768x480.png"},{"@type":"BreadcrumbList","@id":"https:\/\/gradido.net\/what-is-gradido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gradido.net\/"},{"@type":"ListItem","position":2,"name":"Wohlstand"}]},{"@type":"WebSite","@id":"https:\/\/gradido.net\/de\/#website","url":"https:\/\/gradido.net\/de\/","name":"Gradido","description":"Uusi valuutta on kiitollisuus","publisher":{"@id":"https:\/\/gradido.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gradido.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/gradido.net\/de\/#organization","name":"Gradido","url":"https:\/\/gradido.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","width":527,"height":273,"caption":"Gradido"},"image":{"@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/pages\/2118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/comments?post=2118"}],"version-history":[{"count":116,"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/pages\/2118\/revisions"}],"predecessor-version":[{"id":12794,"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/pages\/2118\/revisions\/12794"}],"wp:attachment":[{"href":"https:\/\/gradido.net\/fi\/wp-json\/wp\/v2\/media?parent=2118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}