{"id":6359,"date":"2023-03-03T07:07:47","date_gmt":"2023-03-03T06:07:47","guid":{"rendered":"https:\/\/gradido.net\/?p=6359"},"modified":"2023-03-03T07:08:34","modified_gmt":"2023-03-03T06:08:34","slug":"episode-46","status":"publish","type":"post","link":"https:\/\/gradido.net\/nl\/episode-46\/","title":{"rendered":"Van scheiding naar verbinding"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6359\" class=\"elementor elementor-6359\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-496e1d53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"496e1d53\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-461d7be0\" data-id=\"461d7be0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd9ebe2 elementor-widget elementor-widget-text-editor\" data-id=\"cd9ebe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Gast: Karolin Sch\u00f6nemann en Eugen Litwinenko<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f93e3c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f93e3c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a9dfd19\" data-id=\"5a9dfd19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cdb6b8 elementor-widget elementor-widget-html\" data-id=\"9cdb6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script class=\"podigee-podcast-player\" src=\"https:\/\/player.podigee-cdn.net\/podcast-player\/javascripts\/podigee-podcast-player.js\" data-configuration=\"https:\/\/gradido.podigee.io\/46-new-episode\/embed?context=external&token=NV_-hEDFUBZ_sYI2Hvv2Hw\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-585c640 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"585c640\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13c250b\" data-id=\"13c250b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0561949 elementor-widget elementor-widget-text-editor\" data-id=\"0561949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stel je voor dat dankbaarheid de nieuwe valuta is en wij mensen elkaar liefdevol en waarderend behandelen - zowel priv\u00e9 als in het economische leven! De menselijke familie leeft wereldwijd in welvaart, vrede en vrijheid - in harmonie met de natuur. Dit is de visie van Gradido.<\/p><p>Maar helaas zijn de meesten van ons ernstig getraumatiseerd. Gehechtheids- en ontwikkelingstrauma's ontstaan in de vroege kindertijd, die we ons hele leven in ons dragen en onbewust doorgeven van generatie op generatie. Dit maakt ons gevoelig voor verdeeldheid, manipulatie en concurrentie - zelfs oorlog. Kunnen we deze vicieuze cirkel van traumatisering nog op tijd doorbreken en een goede en vreedzame toekomst voor onze kinderen cre\u00ebren?<\/p><p>In deze aflevering praten we met Karolin Sch\u00f6nemann en Eugen Litwinenko. De twee beoefenen de methode van \"Eerlijk Delen\". Ze zijn enthousiast over deze eenvoudige en effectieve manier om oude trauma's op te lossen en nieuwe positieve ervaringen van veiligheid en geborgenheid op te doen.\u00a0<\/p><p>Het concept van eerlijk delen krijgt steeds meer erkenning. Het is een ander waardevol stukje van de puzzel in het totaalbeeld van onze gemeenschappelijke toekomst - voor onszelf, onze kinderen en alle kinderen van de wereld.<\/p><p>Links:<\/p><p>Karolin Sch\u00f6nemann<\/p><p><a href=\"https:\/\/lebenssinn-berufung.weebly.com\/ehrliches-mitteilen.html\">https:\/\/lebenssinn-berufung.weebly.com\/ehrliches-mitteilen.html<\/a><\/p><p>Gopal Norbert Klein<\/p><p><a href=\"https:\/\/www.traumaheilung.net\/\">https:\/\/www.traumaheilung.net\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e0d795e\" data-id=\"e0d795e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c61bad elementor-widget elementor-widget-image\" data-id=\"8c61bad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-1024x1024.jpg\" class=\"attachment-large size-large wp-image-6347\" alt=\"\" srcset=\"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-1024x1024.jpg 1024w, https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-300x300.jpg 300w, https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-150x150.jpg 150w, https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-768x768.jpg 768w, https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko-12x12.jpg 12w, https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/gradido_podcast_schoenemann_litwinenko.jpg 1400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceab137 elementor-widget elementor-widget-text-editor\" data-id=\"ceab137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/youtu.be\/OdB4ONUqAAQ\" target=\"_blank\" rel=\"noopener\">Luister op YouTube<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d051609 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d051609\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13cc168\" data-id=\"13cc168\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b43b3ee elementor-widget elementor-widget-heading\" data-id=\"b43b3ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transcript (automatisch vertaald)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-474427c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"474427c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6041f12\" data-id=\"6041f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Karolin Sch\u00f6nemann en Eugen Litwinenko over \"Eerlijk delen\". Het concept van traumaverwerking is een ander waardevol stukje van de puzzel van onze gemeenschappelijke toekomst - voor onszelf, onze kinderen en alle kinderen van de wereld.<\/p>","protected":false},"author":12,"featured_media":6348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[14,32,33,34],"class_list":["post-6359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast","tag-finanzsystem","tag-geldsystem","tag-trauma","tag-traumaloesung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aus der Trennung in die Verbindung - Gradido<\/title>\n<meta name=\"description\" content=\"Karolin Sch\u00f6nemann und Eugen Litwinenko \u00fcber das \u201aEhrliche Mitteilen\u2018. Das Konzept zur Trauma-L\u00f6sung ist ein weiterer wertvoller Puzzlestein unserer gemeinsamen guten Zukunft \u2013 f\u00fcr uns selbst, unsere Kinder und alle Kinder der Welt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gradido.net\/nl\/episode-46\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aus der Trennung in die Verbindung - Gradido\" \/>\n<meta property=\"og:description\" content=\"Karolin Sch\u00f6nemann und Eugen Litwinenko \u00fcber das \u201aEhrliche Mitteilen\u2018. Das Konzept zur Trauma-L\u00f6sung ist ein weiterer wertvoller Puzzlestein unserer gemeinsamen guten Zukunft \u2013 f\u00fcr uns selbst, unsere Kinder und alle Kinder der Welt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gradido.net\/nl\/episode-46\/\" \/>\n<meta property=\"og:site_name\" content=\"Gradido\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T06:07:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T06:08:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philipp Kessler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philipp Kessler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/\"},\"author\":{\"name\":\"Philipp Kessler\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/person\\\/f57399104ec77f2a2d5a68f479b0492f\"},\"headline\":\"Aus der Trennung in die Verbindung\",\"datePublished\":\"2023-03-03T06:07:47+00:00\",\"dateModified\":\"2023-03-03T06:08:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/podcast_www_schoenemann_litwinenko.jpg\",\"keywords\":[\"Finanzsystem\",\"Geldsystem\",\"Trauma\",\"Traumal\u00f6sung\"],\"articleSection\":[\"Podcast\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/\",\"name\":\"Aus der Trennung in die Verbindung - Gradido\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/podcast_www_schoenemann_litwinenko.jpg\",\"datePublished\":\"2023-03-03T06:07:47+00:00\",\"dateModified\":\"2023-03-03T06:08:34+00:00\",\"description\":\"Karolin Sch\u00f6nemann und Eugen Litwinenko \u00fcber das \u201aEhrliche Mitteilen\u2018. Das Konzept zur Trauma-L\u00f6sung ist ein weiterer wertvoller Puzzlestein unserer gemeinsamen guten Zukunft \u2013 f\u00fcr uns selbst, unsere Kinder und alle Kinder der Welt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/podcast_www_schoenemann_litwinenko.jpg\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/podcast_www_schoenemann_litwinenko.jpg\",\"width\":700,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gradido.net\\\/tr\\\/episode-46\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gradido.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aus der Trennung in die Verbindung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"name\":\"Gradido\",\"description\":\"Die neue W\u00e4hrung hei\u00dft Dankbarkeit\",\"publisher\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gradido.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#organization\",\"name\":\"Gradido\",\"url\":\"https:\\\/\\\/gradido.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"contentUrl\":\"https:\\\/\\\/gradido.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/gradido-social.jpg\",\"width\":527,\"height\":273,\"caption\":\"Gradido\"},\"image\":{\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gradido.net\\\/de\\\/#\\\/schema\\\/person\\\/f57399104ec77f2a2d5a68f479b0492f\",\"name\":\"Philipp Kessler\",\"url\":\"https:\\\/\\\/gradido.net\\\/nl\\\/author\\\/philipp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Van scheiding naar verbinding - Gradido","description":"Karolin Sch\u00f6nemann en Eugen Litwinenko over \"Eerlijk delen\". Het concept van traumaverwerking is een ander waardevol stukje van de puzzel van onze gemeenschappelijke toekomst - voor onszelf, onze kinderen en alle kinderen van de wereld.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gradido.net\/nl\/episode-46\/","og_locale":"nl_NL","og_type":"article","og_title":"Aus der Trennung in die Verbindung - Gradido","og_description":"Karolin Sch\u00f6nemann und Eugen Litwinenko \u00fcber das \u201aEhrliche Mitteilen\u2018. Das Konzept zur Trauma-L\u00f6sung ist ein weiterer wertvoller Puzzlestein unserer gemeinsamen guten Zukunft \u2013 f\u00fcr uns selbst, unsere Kinder und alle Kinder der Welt.","og_url":"https:\/\/gradido.net\/nl\/episode-46\/","og_site_name":"Gradido","article_published_time":"2023-03-03T06:07:47+00:00","article_modified_time":"2023-03-03T06:08:34+00:00","og_image":[{"width":700,"height":475,"url":"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg","type":"image\/jpeg"}],"author":"Philipp Kessler","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Philipp Kessler","Geschatte leestijd":"3 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gradido.net\/tr\/episode-46\/#article","isPartOf":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/"},"author":{"name":"Philipp Kessler","@id":"https:\/\/gradido.net\/de\/#\/schema\/person\/f57399104ec77f2a2d5a68f479b0492f"},"headline":"Aus der Trennung in die Verbindung","datePublished":"2023-03-03T06:07:47+00:00","dateModified":"2023-03-03T06:08:34+00:00","mainEntityOfPage":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/"},"wordCount":227,"publisher":{"@id":"https:\/\/gradido.net\/de\/#organization"},"image":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/#primaryimage"},"thumbnailUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg","keywords":["Finanzsystem","Geldsystem","Trauma","Traumal\u00f6sung"],"articleSection":["Podcast"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/gradido.net\/tr\/episode-46\/","url":"https:\/\/gradido.net\/tr\/episode-46\/","name":"Van scheiding naar verbinding - Gradido","isPartOf":{"@id":"https:\/\/gradido.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/#primaryimage"},"image":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/#primaryimage"},"thumbnailUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg","datePublished":"2023-03-03T06:07:47+00:00","dateModified":"2023-03-03T06:08:34+00:00","description":"Karolin Sch\u00f6nemann en Eugen Litwinenko over \"Eerlijk delen\". Het concept van traumaverwerking is een ander waardevol stukje van de puzzel van onze gemeenschappelijke toekomst - voor onszelf, onze kinderen en alle kinderen van de wereld.","breadcrumb":{"@id":"https:\/\/gradido.net\/tr\/episode-46\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gradido.net\/tr\/episode-46\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gradido.net\/tr\/episode-46\/#primaryimage","url":"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2023\/02\/podcast_www_schoenemann_litwinenko.jpg","width":700,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/gradido.net\/tr\/episode-46\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gradido.net\/"},{"@type":"ListItem","position":2,"name":"Aus der Trennung in die Verbindung"}]},{"@type":"WebSite","@id":"https:\/\/gradido.net\/de\/#website","url":"https:\/\/gradido.net\/de\/","name":"Gradido","description":"De nieuwe munteenheid is dankbaarheid","publisher":{"@id":"https:\/\/gradido.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gradido.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/gradido.net\/de\/#organization","name":"Gradido","url":"https:\/\/gradido.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","contentUrl":"https:\/\/gradido.net\/wp-content\/uploads\/2022\/04\/gradido-social.jpg","width":527,"height":273,"caption":"Gradido"},"image":{"@id":"https:\/\/gradido.net\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gradido.net\/de\/#\/schema\/person\/f57399104ec77f2a2d5a68f479b0492f","name":"Philipp Kessler","url":"https:\/\/gradido.net\/nl\/author\/philipp\/"}]}},"_links":{"self":[{"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/posts\/6359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/comments?post=6359"}],"version-history":[{"count":8,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/posts\/6359\/revisions"}],"predecessor-version":[{"id":6367,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/posts\/6359\/revisions\/6367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/media\/6348"}],"wp:attachment":[{"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/media?parent=6359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/categories?post=6359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gradido.net\/nl\/wp-json\/wp\/v2\/tags?post=6359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}